{"id":4761,"date":"2024-07-04T07:04:53","date_gmt":"2024-07-04T07:04:53","guid":{"rendered":"https:\/\/www.cars-in-china.com\/?post_type=product&#038;p=4761"},"modified":"2024-09-02T08:53:10","modified_gmt":"2024-09-02T08:53:10","slug":"2024-mercedes-benz-eqb","status":"publish","type":"product","link":"https:\/\/www.cars-in-china.com\/fr\/2024-mercedes-benz-eqb\/","title":{"rendered":"Mercedes-Benz EQB 2024"},"content":{"rendered":"<p>2024 Mercedes-Benz EQB est un SUV vendu par l&#039;exportateur chinois de voitures \u00e9lectriques DUDU NEV (le concessionnaire officiel agr\u00e9\u00e9 de Mercedes). DUDU NEV poss\u00e8de des qualifications d&#039;exportation professionnelles, des qualifications compl\u00e8tes et des proc\u00e9dures d&#039;exportation pratiques et est une unit\u00e9 pilote d&#039;exportation automobile approuv\u00e9e par le minist\u00e8re du Commerce. Il y a maintenant 300 unit\u00e9s en stock sur la voiture disponibles pour exp\u00e9dition en 3 jours et la vitesse de livraison est rapide. La voiture est en vente chaude dans le monde entier.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le Mercedes-Benz EQB 2024 est un SUV vendu par l&#039;exportateur chinois de voitures \u00e9lectriques DUDU NEV (concessionnaire officiel agr\u00e9\u00e9 de Mercedes). DUDU NEV poss\u00e8de des qualifications d&#039;exportation professionnelles, des qualifications compl\u00e8tes et des proc\u00e9dures d&#039;exportation pratiques et est une unit\u00e9 pilote d&#039;exportation automobile approuv\u00e9e par le minist\u00e8re du Commerce. Il y a maintenant 300 unit\u00e9s en stock concernant la voiture disponible pour exp\u00e9dition en 3 jours et la livraison [\u2026]<\/p>","protected":false},"featured_media":4659,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[20,32],"product_tag":[],"class_list":{"0":"post-4761","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-new-car","7":"product_cat-mercedes-benz","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.cars-in-china.com\/fr\/wp-json\/wp\/v2\/product\/4761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cars-in-china.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cars-in-china.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cars-in-china.com\/fr\/wp-json\/wp\/v2\/comments?post=4761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cars-in-china.com\/fr\/wp-json\/wp\/v2\/media\/4659"}],"wp:attachment":[{"href":"https:\/\/www.cars-in-china.com\/fr\/wp-json\/wp\/v2\/media?parent=4761"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cars-in-china.com\/fr\/wp-json\/wp\/v2\/product_brand?post=4761"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cars-in-china.com\/fr\/wp-json\/wp\/v2\/product_cat?post=4761"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cars-in-china.com\/fr\/wp-json\/wp\/v2\/product_tag?post=4761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}